{"id":12709,"date":"2025-04-22T15:11:00","date_gmt":"2025-04-22T13:11:00","guid":{"rendered":"https:\/\/dyloghitech.com\/?post_type=prodotto&#038;p=12709"},"modified":"2025-04-24T12:33:54","modified_gmt":"2025-04-24T10:33:54","slug":"controllo-lattine-2-pezzi","status":"publish","type":"prodotto","link":"https:\/\/dyloghitech.com\/it\/prodotto\/controllo-lattine-2-pezzi\/","title":{"rendered":"Controllo Lattine 2 Pezzi"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"12709\" class=\"elementor elementor-12709\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f9f7562 e-con-full e-flex e-con e-parent\" data-id=\"f9f7562\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2843a8d e-con-full e-flex e-con e-child\" data-id=\"2843a8d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1b81e8f elementor-widget elementor-widget-shortcode\" data-id=\"1b81e8f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"12476\" class=\"elementor elementor-12476\">\n\t\t\t\t<div class=\"elementor-element elementor-element-08b971f e-con-full e-flex e-con e-parent\" data-id=\"08b971f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bad768e elementor-widget elementor-widget-text-editor\" data-id=\"bad768e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Applicazioni \u2013 Laboratory Metrology &#8211;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15d78e4 elementor-widget elementor-widget-hfe-breadcrumbs-widget\" data-id=\"15d78e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"hfe-breadcrumbs-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<nav aria-label=\"Breadcrumb\"><ul class=\"hfe-breadcrumbs \"><\/ul><\/nav>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-755bdf5 e-flex e-con-boxed e-con e-parent\" data-id=\"755bdf5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a610019 e-con-full e-flex e-con e-child\" data-id=\"a610019\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-e26960b e-con-full e-flex e-con e-child\" data-id=\"e26960b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-671219c elementor-widget elementor-widget-image\" data-id=\"671219c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dyloghitech.com\/wp-content\/uploads\/elementor\/thumbs\/Laboratory-Metrology-Logo-Riquadrato-01-qvqcx8vd8ezxmx4hzl4cj45rx7lfho2jpc38vnv9zw.png\" title=\"Laboratory Metrology\" alt=\"Laboratory Metrology\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3d3bf0a e-con-full e-flex e-con e-child\" data-id=\"3d3bf0a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-00e01bc elementor-widget elementor-widget-heading\" data-id=\"00e01bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Laboratory Metrology<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1de1f78 e-flex e-con-boxed e-con e-parent\" data-id=\"1de1f78\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4d6fd4e e-con-full container-menu e-flex e-con e-child\" data-id=\"4d6fd4e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e862840 elementor-widget elementor-widget-shortcode\" data-id=\"e862840\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"12508\" class=\"elementor elementor-12508\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8593de7 e-con-full e-flex e-con e-parent\" data-id=\"8593de7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c3450a0 hfe-nav-menu__align-center hfe-nav-menu__breakpoint-none elementor-widget-mobile__width-inherit hfe-submenu-icon-arrow hfe-link-redirect-child elementor-widget elementor-widget-navigation-menu\" data-id=\"c3450a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;padding_horizontal_menu_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;padding_vertical_menu_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;menu_space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;padding_horizontal_menu_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;padding_vertical_menu_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;menu_space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;padding_horizontal_menu_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_menu_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;dropdown_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;dropdown_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;dropdown_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;padding_horizontal_dropdown_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_dropdown_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_dropdown_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_dropdown_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;padding_vertical_dropdown_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_dropdown_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;distance_from_menu&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;distance_from_menu_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;distance_from_menu_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_size&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_size_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_size_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"navigation-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"hfe-nav-menu hfe-layout-vertical hfe-nav-menu-layout vertical\" data-layout=\"vertical\">\n\t\t\t\t<div role=\"button\" class=\"hfe-nav-menu__toggle elementor-clickable\" tabindex=\"0\" aria-label=\"Menu Toggle\">\n\t\t\t\t\t<span class=\"screen-reader-text\">Menu<\/span>\n\t\t\t\t\t<div class=\"hfe-nav-menu-icon\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<nav class=\"hfe-nav-menu__layout-vertical hfe-nav-menu__submenu-arrow\" data-toggle-icon=\"\" data-close-icon=\"\" data-full-width=\"\">\n\t\t\t\t\t<ul id=\"menu-1-c3450a0\" class=\"hfe-nav-menu\"><li id=\"menu-item-12792\" class=\"menu-item menu-item-type-post_type menu-item-object-prodotto parent hfe-creative-menu\"><a href=\"https:\/\/dyloghitech.com\/it\/prodotto\/controllo-aggraffatura\/\" class = \"hfe-menu-item\">Controllo Aggraffatura<\/a><\/li>\n<li id=\"menu-item-12793\" class=\"menu-item menu-item-type-post_type menu-item-object-prodotto parent hfe-creative-menu\"><a href=\"https:\/\/dyloghitech.com\/it\/prodotto\/controllo-scatole-3-pezzi\/\" class = \"hfe-menu-item\">Controllo Scatole 3 Pezzi<\/a><\/li>\n<li id=\"menu-item-12794\" class=\"menu-item menu-item-type-post_type menu-item-object-prodotto parent hfe-creative-menu\"><a href=\"https:\/\/dyloghitech.com\/it\/prodotto\/controllo-coperchi\/\" class = \"hfe-menu-item\">Controllo Coperchi<\/a><\/li>\n<li id=\"menu-item-12795\" class=\"menu-item menu-item-type-post_type menu-item-object-prodotto parent hfe-creative-menu\"><a href=\"https:\/\/dyloghitech.com\/it\/prodotto\/controllo-contenitori-aerosol\/\" class = \"hfe-menu-item\">Controllo Contenitori Aerosol<\/a><\/li>\n<li id=\"menu-item-12796\" class=\"menu-item menu-item-type-post_type menu-item-object-prodotto parent hfe-creative-menu\"><a href=\"https:\/\/dyloghitech.com\/it\/prodotto\/controlli-verniciatura\/\" class = \"hfe-menu-item\">Controlli Verniciatura<\/a><\/li>\n<li id=\"menu-item-12797\" class=\"menu-item menu-item-type-post_type menu-item-object-prodotto parent hfe-creative-menu\"><a href=\"https:\/\/dyloghitech.com\/it\/prodotto\/controllo-contenitori-in-vetro\/\" class = \"hfe-menu-item\">Controllo Contenitori in Vetro<\/a><\/li>\n<li id=\"menu-item-12798\" class=\"menu-item menu-item-type-post_type menu-item-object-prodotto parent hfe-creative-menu\"><a href=\"https:\/\/dyloghitech.com\/it\/prodotto\/controllo-contenitori-plastica-pet-preforme\/\" class = \"hfe-menu-item\">Controllo Contenitori Plastica &amp; PET-Preforme<\/a><\/li>\n<li id=\"menu-item-12799\" class=\"menu-item menu-item-type-post_type menu-item-object-prodotto parent hfe-creative-menu\"><a href=\"https:\/\/dyloghitech.com\/it\/prodotto\/controllo-lattine-2-pezzi\/\" class = \"hfe-menu-item\">Controllo Lattine 2 Pezzi<\/a><\/li>\n<li id=\"menu-item-12800\" class=\"menu-item menu-item-type-post_type menu-item-object-prodotto parent hfe-creative-menu\"><a href=\"https:\/\/dyloghitech.com\/it\/prodotto\/controlli-birra-e-bevande\/\" class = \"hfe-menu-item\">Controlli Birra &amp; Bevande<\/a><\/li>\n<\/ul> \n\t\t\t\t<\/nav>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-214aaca e-con-full container-content e-flex e-con e-child\" data-id=\"214aaca\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5d2aa59 e-con-full box-prodotto e-flex e-con e-child\" data-id=\"5d2aa59\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a348c76 post-title elementor-widget elementor-widget-heading\" data-id=\"a348c76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wall Thick Check<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f3b89db e-con-full e-flex e-con e-child\" data-id=\"f3b89db\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-c2d096d e-con-full post-info e-flex e-con e-child\" data-id=\"c2d096d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7a9f6d7 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"7a9f6d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:1}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Strumento per la <strong>misura dello spessore del corpo lattina<\/strong>.<br \/>La misura dello spessore del corpo della lattina in punti differenti \u00e8 un <strong>parametro molto importante nel controllo qualit\u00e0<\/strong> nel processo di formatura della scatola.<br \/>La misura viene effettuata per mezzo di una coppia di indicatori digitali Mitutoyo con risoluzione 0,01 mm montati su un apposito supporto.<br \/>\u00c8 <strong>possibile collegare lo strumento di misura con un computer esterno<\/strong> per mezzo dell\u2019apposita interfaccia di comunicazione.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2466048 e-con-full post-image e-flex e-con e-child\" data-id=\"2466048\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-80c65f8 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"80c65f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;jello&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"717\" height=\"787\" src=\"https:\/\/dyloghitech.com\/wp-content\/uploads\/wall-thick-check.png\" class=\"attachment-full size-full wp-image-12711\" alt=\"wall thick check\" srcset=\"https:\/\/dyloghitech.com\/wp-content\/uploads\/wall-thick-check.png 717w, https:\/\/dyloghitech.com\/wp-content\/uploads\/wall-thick-check-273x300.png 273w\" sizes=\"(max-width: 717px) 100vw, 717px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-196c1b2 e-con-full box-prodotto e-flex e-con e-child\" data-id=\"196c1b2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d0901a5 post-title elementor-widget elementor-widget-heading\" data-id=\"d0901a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Inner Diameter Check<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-40dc91e e-con-full e-flex e-con e-child\" data-id=\"40dc91e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-c17dc81 e-con-full post-info e-flex e-con e-child\" data-id=\"c17dc81\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-747e9ca elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"747e9ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:1}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Viene utilizzato per <strong>misurare il diametro interno delle scatole<\/strong> 2\/3 pezzi.<br \/><strong>Disponibile in tre versioni<\/strong> per scatole con differenti diametri: \u2264 69 mm (211); \u2264 105 mm (404); \u2264 153 mm (603).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-99894bf e-con-full post-image e-flex e-con e-child\" data-id=\"99894bf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7b78dd4 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"7b78dd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;jello&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"519\" height=\"370\" src=\"https:\/\/dyloghitech.com\/wp-content\/uploads\/inner-diameter-check_scatole.png\" class=\"attachment-full size-full wp-image-12713\" alt=\"inner diameter check scatole 2 pezzi\" srcset=\"https:\/\/dyloghitech.com\/wp-content\/uploads\/inner-diameter-check_scatole.png 519w, https:\/\/dyloghitech.com\/wp-content\/uploads\/inner-diameter-check_scatole-300x214.png 300w\" sizes=\"(max-width: 519px) 100vw, 519px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dceaac7 e-con-full box-prodotto e-flex e-con e-child\" data-id=\"dceaac7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-29689ec post-title elementor-widget elementor-widget-heading\" data-id=\"29689ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Top Load Check<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-04c3500 e-con-full e-flex e-con e-child\" data-id=\"04c3500\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-7cb4ef4 e-con-full post-info e-flex e-con e-child\" data-id=\"7cb4ef4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-78f82e8 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"78f82e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:1}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Strumento per la <strong>misura del carico assiale<\/strong>.<br \/>Misura la resistenza al carico assiale delle <strong>scatole 2 pezzi<\/strong>.<br \/>La scatola viene sottoposta a una spinta progressiva fino al cedimento. Il <strong>valore della forza<\/strong> in corrispondenza della quale la scatola subisce una deformazione permanente viene registrato e visualizzato sullo schermo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-593cda8 e-con-full post-image e-flex elementor-invisible e-con e-child\" data-id=\"593cda8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;jello&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9c3b6aa elementor-widget elementor-widget-image\" data-id=\"9c3b6aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"682\" height=\"783\" src=\"https:\/\/dyloghitech.com\/wp-content\/uploads\/top-load-check-scatole-2-pezzi.png\" class=\"attachment-full size-full wp-image-12715\" alt=\"\" srcset=\"https:\/\/dyloghitech.com\/wp-content\/uploads\/top-load-check-scatole-2-pezzi.png 682w, https:\/\/dyloghitech.com\/wp-content\/uploads\/top-load-check-scatole-2-pezzi-261x300.png 261w\" sizes=\"(max-width: 682px) 100vw, 682px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-84a478e e-con-full box-prodotto e-flex e-con e-child\" data-id=\"84a478e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-778dd83 post-title elementor-widget elementor-widget-heading\" data-id=\"778dd83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mobility Check<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-818daaf e-con-full e-flex e-con e-child\" data-id=\"818daaf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-eb1c683 e-con-full post-info e-flex e-con e-child\" data-id=\"eb1c683\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e355449 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"e355449\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:1}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Strumento per il <strong>test di mobilit\u00e0<\/strong> (scorrimento).<br \/>Il <strong>tester di lubrificazione per lattine<\/strong> serve per misurare il <strong>coefficiente di attrito radente<\/strong> del corpo e del fondo della lattina.<br \/>Pu\u00f2 anche misurare il coefficiente di attrito radente degli spazi vuoti. Una particolarit\u00e0 \u00e8 la <strong>possibilit\u00e0 di selezionare una modalit\u00e0 di trasmissione di dati dedicata<\/strong> inviando ad un PC esterno i valori misurati (1 valore campione per ogni millimetro).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ff9d423 e-con-full post-image e-flex e-con e-child\" data-id=\"ff9d423\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c5566a elementor-invisible elementor-widget elementor-widget-image\" data-id=\"2c5566a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;jello&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"543\" src=\"https:\/\/dyloghitech.com\/wp-content\/uploads\/mobility-check-scatole-2-pezzi.jpg\" class=\"attachment-full size-full wp-image-12720\" alt=\"mobility check scatole 2 pezzi\" srcset=\"https:\/\/dyloghitech.com\/wp-content\/uploads\/mobility-check-scatole-2-pezzi.jpg 800w, https:\/\/dyloghitech.com\/wp-content\/uploads\/mobility-check-scatole-2-pezzi-300x204.jpg 300w, https:\/\/dyloghitech.com\/wp-content\/uploads\/mobility-check-scatole-2-pezzi-768x521.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Wall Thick Check Strumento per la misura dello spessore del corpo lattina.La misura dello spessore del corpo della lattina in punti differenti \u00e8 un parametro molto importante nel controllo qualit\u00e0 nel processo di formatura della scatola.La misura viene effettuata per mezzo di una coppia di indicatori digitali Mitutoyo con risoluzione 0,01 mm montati su un [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"parent":0,"menu_order":0,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-12709","prodotto","type-prodotto","status-publish","format-standard","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Controllo Lattine 2 Pezzi - Dylog Hitech<\/title>\n<meta name=\"description\" content=\"Strumenti da laboratorio per il controllo di lattine: misura dello spessore del corpo, del diametro interno e del carico assiale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dyloghitech.com\/it\/prodotto\/controllo-lattine-2-pezzi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Controllo Lattine 2 Pezzi - Dylog Hitech\" \/>\n<meta property=\"og:description\" content=\"Strumenti da laboratorio per il controllo di lattine: misura dello spessore del corpo, del diametro interno e del carico assiale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dyloghitech.com\/it\/prodotto\/controllo-lattine-2-pezzi\/\" \/>\n<meta property=\"og:site_name\" content=\"Dylog Hitech\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-24T10:33:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dyloghitech.com\/wp-content\/uploads\/wall-thick-check.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dyloghitech.com\\\/it\\\/prodotto\\\/controllo-lattine-2-pezzi\\\/\",\"url\":\"https:\\\/\\\/dyloghitech.com\\\/it\\\/prodotto\\\/controllo-lattine-2-pezzi\\\/\",\"name\":\"Controllo Lattine 2 Pezzi - Dylog Hitech\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dyloghitech.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dyloghitech.com\\\/it\\\/prodotto\\\/controllo-lattine-2-pezzi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dyloghitech.com\\\/it\\\/prodotto\\\/controllo-lattine-2-pezzi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dyloghitech.com\\\/wp-content\\\/uploads\\\/wall-thick-check.png\",\"datePublished\":\"2025-04-22T13:11:00+00:00\",\"dateModified\":\"2025-04-24T10:33:54+00:00\",\"description\":\"Strumenti da laboratorio per il controllo di lattine: misura dello spessore del corpo, del diametro interno e del carico assiale.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dyloghitech.com\\\/it\\\/prodotto\\\/controllo-lattine-2-pezzi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dyloghitech.com\\\/it\\\/prodotto\\\/controllo-lattine-2-pezzi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/dyloghitech.com\\\/it\\\/prodotto\\\/controllo-lattine-2-pezzi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dyloghitech.com\\\/wp-content\\\/uploads\\\/wall-thick-check.png\",\"contentUrl\":\"https:\\\/\\\/dyloghitech.com\\\/wp-content\\\/uploads\\\/wall-thick-check.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dyloghitech.com\\\/it\\\/prodotto\\\/controllo-lattine-2-pezzi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dyloghitech.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Controllo Lattine 2 Pezzi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dyloghitech.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/dyloghitech.com\\\/it\\\/\",\"name\":\"Dylog Hitech\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/dyloghitech.com\\\/it\\\/#organization\"},\"alternateName\":\"Dylog Hitech\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dyloghitech.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dyloghitech.com\\\/it\\\/#organization\",\"name\":\"Dylog Hitech\",\"url\":\"https:\\\/\\\/dyloghitech.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/dyloghitech.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dyloghitech.com\\\/wp-content\\\/uploads\\\/cropped-Dylog-Hitech-Logo01-01.png\",\"contentUrl\":\"https:\\\/\\\/dyloghitech.com\\\/wp-content\\\/uploads\\\/cropped-Dylog-Hitech-Logo01-01.png\",\"width\":404,\"height\":150,\"caption\":\"Dylog Hitech\"},\"image\":{\"@id\":\"https:\\\/\\\/dyloghitech.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Controllo Lattine 2 Pezzi - Dylog Hitech","description":"Strumenti da laboratorio per il controllo di lattine: misura dello spessore del corpo, del diametro interno e del carico assiale.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dyloghitech.com\/it\/prodotto\/controllo-lattine-2-pezzi\/","og_locale":"it_IT","og_type":"article","og_title":"Controllo Lattine 2 Pezzi - Dylog Hitech","og_description":"Strumenti da laboratorio per il controllo di lattine: misura dello spessore del corpo, del diametro interno e del carico assiale.","og_url":"https:\/\/dyloghitech.com\/it\/prodotto\/controllo-lattine-2-pezzi\/","og_site_name":"Dylog Hitech","article_modified_time":"2025-04-24T10:33:54+00:00","og_image":[{"url":"https:\/\/dyloghitech.com\/wp-content\/uploads\/wall-thick-check.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dyloghitech.com\/it\/prodotto\/controllo-lattine-2-pezzi\/","url":"https:\/\/dyloghitech.com\/it\/prodotto\/controllo-lattine-2-pezzi\/","name":"Controllo Lattine 2 Pezzi - Dylog Hitech","isPartOf":{"@id":"https:\/\/dyloghitech.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dyloghitech.com\/it\/prodotto\/controllo-lattine-2-pezzi\/#primaryimage"},"image":{"@id":"https:\/\/dyloghitech.com\/it\/prodotto\/controllo-lattine-2-pezzi\/#primaryimage"},"thumbnailUrl":"https:\/\/dyloghitech.com\/wp-content\/uploads\/wall-thick-check.png","datePublished":"2025-04-22T13:11:00+00:00","dateModified":"2025-04-24T10:33:54+00:00","description":"Strumenti da laboratorio per il controllo di lattine: misura dello spessore del corpo, del diametro interno e del carico assiale.","breadcrumb":{"@id":"https:\/\/dyloghitech.com\/it\/prodotto\/controllo-lattine-2-pezzi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dyloghitech.com\/it\/prodotto\/controllo-lattine-2-pezzi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/dyloghitech.com\/it\/prodotto\/controllo-lattine-2-pezzi\/#primaryimage","url":"https:\/\/dyloghitech.com\/wp-content\/uploads\/wall-thick-check.png","contentUrl":"https:\/\/dyloghitech.com\/wp-content\/uploads\/wall-thick-check.png"},{"@type":"BreadcrumbList","@id":"https:\/\/dyloghitech.com\/it\/prodotto\/controllo-lattine-2-pezzi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dyloghitech.com\/it\/"},{"@type":"ListItem","position":2,"name":"Controllo Lattine 2 Pezzi"}]},{"@type":"WebSite","@id":"https:\/\/dyloghitech.com\/it\/#website","url":"https:\/\/dyloghitech.com\/it\/","name":"Dylog Hitech","description":"","publisher":{"@id":"https:\/\/dyloghitech.com\/it\/#organization"},"alternateName":"Dylog Hitech","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dyloghitech.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/dyloghitech.com\/it\/#organization","name":"Dylog Hitech","url":"https:\/\/dyloghitech.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/dyloghitech.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/dyloghitech.com\/wp-content\/uploads\/cropped-Dylog-Hitech-Logo01-01.png","contentUrl":"https:\/\/dyloghitech.com\/wp-content\/uploads\/cropped-Dylog-Hitech-Logo01-01.png","width":404,"height":150,"caption":"Dylog Hitech"},"image":{"@id":"https:\/\/dyloghitech.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dyloghitech.com\/it\/wp-json\/wp\/v2\/prodotto\/12709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dyloghitech.com\/it\/wp-json\/wp\/v2\/prodotto"}],"about":[{"href":"https:\/\/dyloghitech.com\/it\/wp-json\/wp\/v2\/types\/prodotto"}],"author":[{"embeddable":true,"href":"https:\/\/dyloghitech.com\/it\/wp-json\/wp\/v2\/users\/8"}],"version-history":[{"count":10,"href":"https:\/\/dyloghitech.com\/it\/wp-json\/wp\/v2\/prodotto\/12709\/revisions"}],"predecessor-version":[{"id":13556,"href":"https:\/\/dyloghitech.com\/it\/wp-json\/wp\/v2\/prodotto\/12709\/revisions\/13556"}],"wp:attachment":[{"href":"https:\/\/dyloghitech.com\/it\/wp-json\/wp\/v2\/media?parent=12709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}